{"id":3393,"date":"2016-08-20T23:03:29","date_gmt":"2016-08-20T23:03:29","guid":{"rendered":"https:\/\/jesuschristformuslims.com\/de\/?p=3393"},"modified":"2016-08-20T23:03:29","modified_gmt":"2016-08-20T23:03:29","slug":"gebet-zum-heiligen-geist","status":"publish","type":"post","link":"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/","title":{"rendered":"Gebet zum Heiligen Geist"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Komm, Heiliger Geist, erf\u00fclle mein Herz mit Deinen Heiligen Gaben. Lass meine Schwachheit mit Deiner St\u00e4rke gerade in diesen Tagen durchdrungen sein, sodass ich alle Pflichten meines Lebens erf\u00fcllen mag, dass ich das Richtige und Rechte zu tun vermag.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Lass meine N\u00e4chstenliebe eine solche sein, die niemanden angreift und niemandes Gef\u00fchle verletzt; so gro\u00dfz\u00fcgig, dass sie aufrichtig alles Schlechte, das man mir angetan, entschuldigt. Stehe mir, O Heiliger Geist, in all meinen Widrigkeiten des Lebens bei, erleuchte mich in meinem Unwissen, berate mich in meinen Zweifeln, st\u00e4rke mich in meiner Schwachheit, hilf mir in all meinen N\u00f6ten, besch\u00fctze mich in Versuchungen und tr\u00f6ste mich in der Bedr\u00e4ngnis.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Gn\u00e4digerweise erh\u00f6re mich, O Heiliger Geist, und gie\u00dfe Dein Licht in mein Herz, in meine Seele, in meinen Geist. Hilf mir, ein Heiliges Leben zu leben und in G\u00fcte und Gnade zu wachsen. Amen.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Komm, Heiliger Geist, erf\u00fclle mein Herz mit Deinen Heiligen Gaben. Lass meine Schwachheit mit Deiner St\u00e4rke gerade in diesen Tagen durchdrungen sein, sodass ich alle Pflichten meines Lebens erf\u00fcllen mag, dass ich das Richtige und Rechte zu tun vermag. Lass meine N\u00e4chstenliebe eine solche sein, die niemanden angreift und niemandes Gef\u00fchle verletzt; so gro\u00dfz\u00fcgig, dass&hellip; <a class=\"more-link\" href=\"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/\"><span class=\"screen-reader-text\">Gebet zum Heiligen Geist<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":4,"featured_media":3394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[1448,1446],"tags":[],"class_list":["post-3393","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-gebete","category-unkategorisiert","post_format-post-format-video","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gebet zum Heiligen Geist - Jesus Christus f\u00fcr Muslime<\/title>\n<meta name=\"description\" content=\"Komm, Heiliger Geist, erf\u00fclle mein Herz mit Deinen Heiligen Gaben. Lass meine Schwachheit mit Deiner St\u00e4rke gerade in diesen Tagen durchdrungen sein, sodass\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gebet zum Heiligen Geist - Jesus Christus f\u00fcr Muslime\" \/>\n<meta property=\"og:description\" content=\"Komm, Heiliger Geist, erf\u00fclle mein Herz mit Deinen Heiligen Gaben. Lass meine Schwachheit mit Deiner St\u00e4rke gerade in diesen Tagen durchdrungen sein, sodass\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/\" \/>\n<meta property=\"og:site_name\" content=\"Jesus Christ for Muslims\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-20T23:03:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2016\/08\/Gebet-zum-Heiligen-Geist-Jesus-Christus-f\u00fcr-Muslime.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Rothfuss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Rothfuss\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/gebet-zum-heiligen-geist\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/gebet-zum-heiligen-geist\\\/\"},\"author\":{\"name\":\"David Rothfuss\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#\\\/schema\\\/person\\\/f6120ac59bddfd1d31b3ed5154d08424\"},\"headline\":\"Gebet zum Heiligen Geist\",\"datePublished\":\"2016-08-20T23:03:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/gebet-zum-heiligen-geist\\\/\"},\"wordCount\":161,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/gebet-zum-heiligen-geist\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jesuschristformuslims.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Gebet-zum-Heiligen-Geist-Jesus-Christus-f\u00fcr-Muslime.jpg\",\"articleSection\":[\"Gebete\",\"Unkategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/gebet-zum-heiligen-geist\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/gebet-zum-heiligen-geist\\\/\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/gebet-zum-heiligen-geist\\\/\",\"name\":\"Gebet zum Heiligen Geist - Jesus Christus f\u00fcr Muslime\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/gebet-zum-heiligen-geist\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/gebet-zum-heiligen-geist\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jesuschristformuslims.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Gebet-zum-Heiligen-Geist-Jesus-Christus-f\u00fcr-Muslime.jpg\",\"datePublished\":\"2016-08-20T23:03:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#\\\/schema\\\/person\\\/f6120ac59bddfd1d31b3ed5154d08424\"},\"description\":\"Komm, Heiliger Geist, erf\u00fclle mein Herz mit Deinen Heiligen Gaben. Lass meine Schwachheit mit Deiner St\u00e4rke gerade in diesen Tagen durchdrungen sein, sodass\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/gebet-zum-heiligen-geist\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/gebet-zum-heiligen-geist\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/gebet-zum-heiligen-geist\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Gebet-zum-Heiligen-Geist-Jesus-Christus-f\u00fcr-Muslime.jpg\",\"contentUrl\":\"https:\\\/\\\/jesuschristformuslims.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Gebet-zum-Heiligen-Geist-Jesus-Christus-f\u00fcr-Muslime.jpg\",\"width\":1920,\"height\":1200,\"caption\":\"Gebet zum Heiligen Geist - Jesus Christus f\u00fcr Muslime\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/gebet-zum-heiligen-geist\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gebet zum Heiligen Geist\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/\",\"name\":\"Jesus Christ for Muslims\",\"description\":\"Inviting Muslims to the Kingdom of Christ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jesuschristformuslims.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#\\\/schema\\\/person\\\/f6120ac59bddfd1d31b3ed5154d08424\",\"name\":\"David Rothfuss\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g\",\"caption\":\"David Rothfuss\"},\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/de\\\/author\\\/david-rothfuss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gebet zum Heiligen Geist - Jesus Christus f\u00fcr Muslime","description":"Komm, Heiliger Geist, erf\u00fclle mein Herz mit Deinen Heiligen Gaben. Lass meine Schwachheit mit Deiner St\u00e4rke gerade in diesen Tagen durchdrungen sein, sodass","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/","og_locale":"de_DE","og_type":"article","og_title":"Gebet zum Heiligen Geist - Jesus Christus f\u00fcr Muslime","og_description":"Komm, Heiliger Geist, erf\u00fclle mein Herz mit Deinen Heiligen Gaben. Lass meine Schwachheit mit Deiner St\u00e4rke gerade in diesen Tagen durchdrungen sein, sodass","og_url":"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/","og_site_name":"Jesus Christ for Muslims","article_published_time":"2016-08-20T23:03:29+00:00","og_image":[{"width":1920,"height":1200,"url":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2016\/08\/Gebet-zum-Heiligen-Geist-Jesus-Christus-f\u00fcr-Muslime.jpg","type":"image\/jpeg"}],"author":"David Rothfuss","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"David Rothfuss","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/#article","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/"},"author":{"name":"David Rothfuss","@id":"https:\/\/jesuschristformuslims.com\/#\/schema\/person\/f6120ac59bddfd1d31b3ed5154d08424"},"headline":"Gebet zum Heiligen Geist","datePublished":"2016-08-20T23:03:29+00:00","mainEntityOfPage":{"@id":"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/"},"wordCount":161,"commentCount":0,"image":{"@id":"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/#primaryimage"},"thumbnailUrl":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2016\/08\/Gebet-zum-Heiligen-Geist-Jesus-Christus-f\u00fcr-Muslime.jpg","articleSection":["Gebete","Unkategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/","url":"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/","name":"Gebet zum Heiligen Geist - Jesus Christus f\u00fcr Muslime","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/#primaryimage"},"image":{"@id":"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/#primaryimage"},"thumbnailUrl":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2016\/08\/Gebet-zum-Heiligen-Geist-Jesus-Christus-f\u00fcr-Muslime.jpg","datePublished":"2016-08-20T23:03:29+00:00","author":{"@id":"https:\/\/jesuschristformuslims.com\/#\/schema\/person\/f6120ac59bddfd1d31b3ed5154d08424"},"description":"Komm, Heiliger Geist, erf\u00fclle mein Herz mit Deinen Heiligen Gaben. Lass meine Schwachheit mit Deiner St\u00e4rke gerade in diesen Tagen durchdrungen sein, sodass","breadcrumb":{"@id":"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/#primaryimage","url":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2016\/08\/Gebet-zum-Heiligen-Geist-Jesus-Christus-f\u00fcr-Muslime.jpg","contentUrl":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2016\/08\/Gebet-zum-Heiligen-Geist-Jesus-Christus-f\u00fcr-Muslime.jpg","width":1920,"height":1200,"caption":"Gebet zum Heiligen Geist - Jesus Christus f\u00fcr Muslime"},{"@type":"BreadcrumbList","@id":"https:\/\/jesuschristformuslims.com\/de\/gebet-zum-heiligen-geist\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jesuschristformuslims.com\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Gebet zum Heiligen Geist"}]},{"@type":"WebSite","@id":"https:\/\/jesuschristformuslims.com\/#website","url":"https:\/\/jesuschristformuslims.com\/","name":"Jesus Christ for Muslims","description":"Inviting Muslims to the Kingdom of Christ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jesuschristformuslims.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/jesuschristformuslims.com\/#\/schema\/person\/f6120ac59bddfd1d31b3ed5154d08424","name":"David Rothfuss","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g","caption":"David Rothfuss"},"url":"https:\/\/jesuschristformuslims.com\/de\/author\/david-rothfuss\/"}]}},"_links":{"self":[{"href":"https:\/\/jesuschristformuslims.com\/de\/wp-json\/wp\/v2\/posts\/3393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jesuschristformuslims.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jesuschristformuslims.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/de\/wp-json\/wp\/v2\/comments?post=3393"}],"version-history":[{"count":1,"href":"https:\/\/jesuschristformuslims.com\/de\/wp-json\/wp\/v2\/posts\/3393\/revisions"}],"predecessor-version":[{"id":3395,"href":"https:\/\/jesuschristformuslims.com\/de\/wp-json\/wp\/v2\/posts\/3393\/revisions\/3395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/de\/wp-json\/wp\/v2\/media\/3394"}],"wp:attachment":[{"href":"https:\/\/jesuschristformuslims.com\/de\/wp-json\/wp\/v2\/media?parent=3393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/de\/wp-json\/wp\/v2\/categories?post=3393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/de\/wp-json\/wp\/v2\/tags?post=3393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}