{"id":7199,"date":"2018-07-11T10:59:27","date_gmt":"2018-07-11T10:59:27","guid":{"rendered":"https:\/\/jesuschristformuslims.com\/?p=7199\/"},"modified":"2018-10-06T11:46:26","modified_gmt":"2018-10-06T11:46:26","slug":"dios-aborrece-los-orgullosos-y-altivos-de-corazon","status":"publish","type":"post","link":"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/","title":{"rendered":"Dios aborrece a los orgullosos y altivos de coraz\u00f3n"},"content":{"rendered":"<p><strong>Proverbios 27:1<\/strong> &#8211; No te jactes del ma\u00f1ana, ya que no sabes lo que el d\u00eda traer\u00e1. Dios aborrece<\/p>\n<p>El mensaje de hoy es algo que a menudo se olvida cuando el ego nos supera. La muerte y los l\u00edmites del tiempo son misterios poco entendibles para el hombre, no hay forma alguna de saber cu\u00e1ndo llegar\u00e1 nuestro fin. El mensaje de proverbios dice que no debemos preocuparnos del ma\u00f1ana o alegrarnos del ma\u00f1ana, porque no sabemos qu\u00e9 pasar\u00e1 ma\u00f1ana, es incierto y desconocido. Lo m\u00e1s sabio es poner en las manos del Se\u00f1or el ma\u00f1ana y preocuparnos por el presente.<\/p>\n<p>A menudo nos comportamos de manera arrogante y despectiva hacia nuestro futuro, olvidando la diferencia que hay entre las buenas y malas acciones. Olvidamos que nuestro tiempo en la tierra es corto y no para siempre. A Dios no le gusta el hombre vanidoso, altivo y orgulloso. Dios ama a aquellos que son generosos de coraz\u00f3n, simples de esp\u00edritu y necesidades. Debes abstenerte de la queja que quieras presentar sobre tu presente o tu futuro, Dios siempre tiene lo mejor preparado para ti, te da todo lo que necesitas. Am\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proverbios 27:1 &#8211; No te jactes del ma\u00f1ana, ya que no sabes lo que el d\u00eda traer\u00e1. Dios aborrece El mensaje de hoy es algo que a menudo se olvida cuando el ego nos supera. La muerte y los l\u00edmites del tiempo son misterios poco entendibles para el hombre, no hay forma alguna de saber&hellip; <a class=\"more-link\" href=\"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/\">Seguir leyendo <span class=\"screen-reader-text\">Dios aborrece a los orgullosos y altivos de coraz\u00f3n<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":7207,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[153,407],"tags":[6327,6328,6331,6329,6330,6332],"class_list":["post-7199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bienvenida","category-mensaje-del-dia","tag-aborrecer","tag-altivos","tag-ego","tag-orgullosos","tag-proverbios-271","tag-vanidad","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dios aborrece a los orgullosos y altivos de coraz\u00f3n | Musulmanes y Cristianos<\/title>\n<meta name=\"description\" content=\"Dios aborrece - Proverbios 27:1 - No te jactes del ma\u00f1ana, ya que no sabes lo que el d\u00eda traer\u00e1. El mensaje de hoy es algo que a menudo se olvida cuando e..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dios aborrece a los orgullosos y altivos de coraz\u00f3n | Musulmanes y Cristianos\" \/>\n<meta property=\"og:description\" content=\"Dios aborrece - Proverbios 27:1 - No te jactes del ma\u00f1ana, ya que no sabes lo que el d\u00eda traer\u00e1. El mensaje de hoy es algo que a menudo se olvida cuando e..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/\" \/>\n<meta property=\"og:site_name\" content=\"Jesus Christ for Muslims\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-11T10:59:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-06T11:46:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2018\/07\/Dios-aborrece-a-los-orgullosos-y-altivos-de-coraz\u00f3n-Musulmanes-y-Cristianos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1076\" \/>\n\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Rothfuss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Rothfuss\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\\\/\"},\"author\":{\"name\":\"David Rothfuss\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#\\\/schema\\\/person\\\/f6120ac59bddfd1d31b3ed5154d08424\"},\"headline\":\"Dios aborrece a los orgullosos y altivos de coraz\u00f3n\",\"datePublished\":\"2018-07-11T10:59:27+00:00\",\"dateModified\":\"2018-10-06T11:46:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\\\/\"},\"wordCount\":213,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jesuschristformuslims.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Dios-aborrece-a-los-orgullosos-y-altivos-de-coraz\u00f3n-Musulmanes-y-Cristianos.jpg\",\"keywords\":[\"Aborrecer\",\"Altivos\",\"Ego\",\"Orgullosos\",\"Proverbios 27:1\",\"Vanidad\"],\"articleSection\":[\"Bienvenida\",\"Mensaje del D\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\\\/\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\\\/\",\"name\":\"Dios aborrece a los orgullosos y altivos de coraz\u00f3n | Musulmanes y Cristianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jesuschristformuslims.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Dios-aborrece-a-los-orgullosos-y-altivos-de-coraz\u00f3n-Musulmanes-y-Cristianos.jpg\",\"datePublished\":\"2018-07-11T10:59:27+00:00\",\"dateModified\":\"2018-10-06T11:46:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#\\\/schema\\\/person\\\/f6120ac59bddfd1d31b3ed5154d08424\"},\"description\":\"Dios aborrece - Proverbios 27:1 - No te jactes del ma\u00f1ana, ya que no sabes lo que el d\u00eda traer\u00e1. El mensaje de hoy es algo que a menudo se olvida cuando e..\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Dios-aborrece-a-los-orgullosos-y-altivos-de-coraz\u00f3n-Musulmanes-y-Cristianos.jpg\",\"contentUrl\":\"https:\\\/\\\/jesuschristformuslims.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Dios-aborrece-a-los-orgullosos-y-altivos-de-coraz\u00f3n-Musulmanes-y-Cristianos.jpg\",\"width\":1076,\"height\":524,\"caption\":\"Dios aborrece a los orgullosos y altivos de coraz\u00f3n | Musulmanes y Cristianos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dios aborrece a los orgullosos y altivos de coraz\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/\",\"name\":\"Jesus Christ for Muslims\",\"description\":\"Inviting Muslims to the Kingdom of Christ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jesuschristformuslims.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#\\\/schema\\\/person\\\/f6120ac59bddfd1d31b3ed5154d08424\",\"name\":\"David Rothfuss\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g\",\"caption\":\"David Rothfuss\"},\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/author\\\/david-rothfuss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dios aborrece a los orgullosos y altivos de coraz\u00f3n | Musulmanes y Cristianos","description":"Dios aborrece - Proverbios 27:1 - No te jactes del ma\u00f1ana, ya que no sabes lo que el d\u00eda traer\u00e1. El mensaje de hoy es algo que a menudo se olvida cuando e..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/","og_locale":"es_ES","og_type":"article","og_title":"Dios aborrece a los orgullosos y altivos de coraz\u00f3n | Musulmanes y Cristianos","og_description":"Dios aborrece - Proverbios 27:1 - No te jactes del ma\u00f1ana, ya que no sabes lo que el d\u00eda traer\u00e1. El mensaje de hoy es algo que a menudo se olvida cuando e..","og_url":"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/","og_site_name":"Jesus Christ for Muslims","article_published_time":"2018-07-11T10:59:27+00:00","article_modified_time":"2018-10-06T11:46:26+00:00","og_image":[{"width":1076,"height":524,"url":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2018\/07\/Dios-aborrece-a-los-orgullosos-y-altivos-de-coraz\u00f3n-Musulmanes-y-Cristianos.jpg","type":"image\/jpeg"}],"author":"David Rothfuss","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David Rothfuss","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/#article","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/"},"author":{"name":"David Rothfuss","@id":"https:\/\/jesuschristformuslims.com\/#\/schema\/person\/f6120ac59bddfd1d31b3ed5154d08424"},"headline":"Dios aborrece a los orgullosos y altivos de coraz\u00f3n","datePublished":"2018-07-11T10:59:27+00:00","dateModified":"2018-10-06T11:46:26+00:00","mainEntityOfPage":{"@id":"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/"},"wordCount":213,"commentCount":0,"image":{"@id":"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/#primaryimage"},"thumbnailUrl":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2018\/07\/Dios-aborrece-a-los-orgullosos-y-altivos-de-coraz\u00f3n-Musulmanes-y-Cristianos.jpg","keywords":["Aborrecer","Altivos","Ego","Orgullosos","Proverbios 27:1","Vanidad"],"articleSection":["Bienvenida","Mensaje del D\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/","url":"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/","name":"Dios aborrece a los orgullosos y altivos de coraz\u00f3n | Musulmanes y Cristianos","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/#primaryimage"},"image":{"@id":"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/#primaryimage"},"thumbnailUrl":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2018\/07\/Dios-aborrece-a-los-orgullosos-y-altivos-de-coraz\u00f3n-Musulmanes-y-Cristianos.jpg","datePublished":"2018-07-11T10:59:27+00:00","dateModified":"2018-10-06T11:46:26+00:00","author":{"@id":"https:\/\/jesuschristformuslims.com\/#\/schema\/person\/f6120ac59bddfd1d31b3ed5154d08424"},"description":"Dios aborrece - Proverbios 27:1 - No te jactes del ma\u00f1ana, ya que no sabes lo que el d\u00eda traer\u00e1. El mensaje de hoy es algo que a menudo se olvida cuando e..","breadcrumb":{"@id":"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/#primaryimage","url":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2018\/07\/Dios-aborrece-a-los-orgullosos-y-altivos-de-coraz\u00f3n-Musulmanes-y-Cristianos.jpg","contentUrl":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2018\/07\/Dios-aborrece-a-los-orgullosos-y-altivos-de-coraz\u00f3n-Musulmanes-y-Cristianos.jpg","width":1076,"height":524,"caption":"Dios aborrece a los orgullosos y altivos de coraz\u00f3n | Musulmanes y Cristianos"},{"@type":"BreadcrumbList","@id":"https:\/\/jesuschristformuslims.com\/es\/dios-aborrece-los-orgullosos-y-altivos-de-corazon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jesuschristformuslims.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Dios aborrece a los orgullosos y altivos de coraz\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/jesuschristformuslims.com\/#website","url":"https:\/\/jesuschristformuslims.com\/","name":"Jesus Christ for Muslims","description":"Inviting Muslims to the Kingdom of Christ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jesuschristformuslims.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/jesuschristformuslims.com\/#\/schema\/person\/f6120ac59bddfd1d31b3ed5154d08424","name":"David Rothfuss","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g","caption":"David Rothfuss"},"url":"https:\/\/jesuschristformuslims.com\/es\/author\/david-rothfuss\/"}]}},"_links":{"self":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts\/7199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/comments?post=7199"}],"version-history":[{"count":1,"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts\/7199\/revisions"}],"predecessor-version":[{"id":7208,"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts\/7199\/revisions\/7208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/media\/7207"}],"wp:attachment":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/media?parent=7199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/categories?post=7199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags?post=7199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}