{"id":7478,"date":"2018-07-23T13:51:07","date_gmt":"2018-07-23T13:51:07","guid":{"rendered":"https:\/\/jesuschristformuslims.com\/?p=7478\/"},"modified":"2018-10-05T13:59:21","modified_gmt":"2018-10-05T13:59:21","slug":"la-vida-de-los-apostatas-del-islam","status":"publish","type":"post","link":"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/","title":{"rendered":"La vida de los ap\u00f3statas del Islam"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La vida de los ap\u00f3statas del Islam en Pakist\u00e1n.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Se dice que los ap\u00f3statas del Islam han ganado un billete de ida al infierno. Hasta donde yo s\u00e9, literalmente se han salvado del infierno. La identidad de Pakist\u00e1n es la fe. Es el \u00fanico pa\u00eds que su base est\u00e1 fundada sobre la fe; aunque Israel fue fundado para los jud\u00edos, siempre fue una sociedad secular. Pakist\u00e1n se convierte en un pa\u00eds fr\u00e1gil si le quitas la religi\u00f3n, las personas fusionan subconscientemente la fe y la identidad nacional todo el tiempo. La obsesi\u00f3n de Pakist\u00e1n para la religi\u00f3n y el terrorismo religioso que lo acompa\u00f1a es algo que ni siguiera los expertos pueden explicar. Los ap\u00f3statas del Islam a menudo ocultan su \u201ctraici\u00f3n al Islam\u201d porque tienen que mantener sus corazones latiendo con fuerza. En una sociedad tan religiosa, es imposible evitar las discusiones isl\u00e1micas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Los musulmanes liberales defienden lo que dice el Cor\u00e1n sobre la apostas\u00eda, moldean los hechos y hacen los castigos \u201cmenos severos\u201d, pero est\u00e1 bastante claro en el Cor\u00e1n, hay que matar a todos aquellos que abandonan el Islam.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Nasai Vol.5, Libro 1, Hadith 4053: <\/strong>El profeta dijo: \u201cNo est\u00e1 permitido derramar la sangre de un musulm\u00e1n excepto en tres casos: un ad\u00faltero que hab\u00eda estado casado, tiene que ser apedreado hasta la muerte\u201d, un hombre que mat\u00f3 a otro hombre intencionalmente, deber\u00eda ser asesinado; y un hombre que abandon\u00f3 el Islam y lucho contra Al\u00e1, el Poderoso y Sublime, y su enviado, que deber\u00eda ser asesinado o crucificado o desterrado de la tierra.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Muchos musulmanes abrazan a Jesucristo con el coraz\u00f3n, pero no se bautizan y practican el cristianismo debido al temor de ser brutalmente asesinados. Dejar el Islam en Pakist\u00e1n no se trata solo de dejar una religi\u00f3n, se trata de dejar a toda la familia, ser rechazado por la sociedad, y correr el riesgo\u00a0verdadero de ser asesinado por los\u00a0radicales del Islam\u00a0(musulmanes devotos). Se convierte en una\u00a0verg\u00fcenza\u00a0que una familia musulmana promedio\u00a0tiene relaciones con los ap\u00f3statas. Muchos practican el cristianismo en secreto, pero los que se descubre que est\u00e1n traicionando son castigados hasta el punto de ser quemados vivos o electrocutados hasta la muerte. Esta es la intolerancia que ense\u00f1a el Cor\u00e1n y la religi\u00f3n obsesionada con la sociedad de Pakist\u00e1n va un paso m\u00e1s all\u00e1 al dar la muerte m\u00e1s dolorosa. Esto tambi\u00e9n pretende ser un ejemplo para los dem\u00e1s, por lo que nadie piensa siquiera en abrazar el cristianismo en el futuro. Este temor ni siquiera permite a los musulmanes investigar el cristianismo. Se vuelven reacios a creer lo que est\u00e1n viendo porque en sus mentes subconscientes conocen el castigo inminente que tendr\u00e1n que sufrir por la sociedad y la familia, y mucho menos por Al\u00e1.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Mazhar Nathaniel<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Amsterdam, Holanda<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vida de los ap\u00f3statas del Islam en Pakist\u00e1n. Se dice que los ap\u00f3statas del Islam han ganado un billete de ida al infierno. Hasta donde yo s\u00e9, literalmente se han salvado del infierno. La identidad de Pakist\u00e1n es la fe. Es el \u00fanico pa\u00eds que su base est\u00e1 fundada sobre la fe; aunque Israel&hellip; <a class=\"more-link\" href=\"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/\">Seguir leyendo <span class=\"screen-reader-text\">La vida de los ap\u00f3statas del Islam<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":7479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[153,405],"tags":[1818,3554,1823,1761,355],"class_list":["post-7478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bienvenida","category-blog-es","tag-apostata","tag-apostata-del-islam","tag-biblia","tag-coran","tag-pakistan","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La vida de los ap\u00f3statas del Islam | Evangelizar Musulm\u00e1n | Cor\u00e1n y la Biblia<\/title>\n<meta name=\"description\" content=\"La vida de los ap\u00f3statas del Islam en Pakist\u00e1n. Se dice que los ap\u00f3statas del Islam han ganado un billete de ida al infierno. Hasta donde yo s\u00e9, literalment\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vida de los ap\u00f3statas del Islam | Evangelizar Musulm\u00e1n | Cor\u00e1n y la Biblia\" \/>\n<meta property=\"og:description\" content=\"La vida de los ap\u00f3statas del Islam en Pakist\u00e1n. Se dice que los ap\u00f3statas del Islam han ganado un billete de ida al infierno. Hasta donde yo s\u00e9, literalment\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/\" \/>\n<meta property=\"og:site_name\" content=\"Jesus Christ for Muslims\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-23T13:51:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-05T13:59:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2018\/07\/La-vida-de-los-ap\u00f3statas-del-Islam-Evangelizar-Musulm\u00e1n-Cor\u00e1n-y-la-Biblia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Rothfuss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Rothfuss\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/la-vida-de-los-apostatas-del-islam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/la-vida-de-los-apostatas-del-islam\\\/\"},\"author\":{\"name\":\"David Rothfuss\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#\\\/schema\\\/person\\\/f6120ac59bddfd1d31b3ed5154d08424\"},\"headline\":\"La vida de los ap\u00f3statas del Islam\",\"datePublished\":\"2018-07-23T13:51:07+00:00\",\"dateModified\":\"2018-10-05T13:59:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/la-vida-de-los-apostatas-del-islam\\\/\"},\"wordCount\":509,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/la-vida-de-los-apostatas-del-islam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jesuschristformuslims.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/La-vida-de-los-ap\u00f3statas-del-Islam-Evangelizar-Musulm\u00e1n-Cor\u00e1n-y-la-Biblia.jpg\",\"keywords\":[\"ap\u00f3stata\",\"Ap\u00f3stata Del Islam\",\"Biblia\",\"Cor\u00e1n\",\"pakistan\"],\"articleSection\":[\"Bienvenida\",\"Blog\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/la-vida-de-los-apostatas-del-islam\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/la-vida-de-los-apostatas-del-islam\\\/\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/la-vida-de-los-apostatas-del-islam\\\/\",\"name\":\"La vida de los ap\u00f3statas del Islam | Evangelizar Musulm\u00e1n | Cor\u00e1n y la Biblia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/la-vida-de-los-apostatas-del-islam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/la-vida-de-los-apostatas-del-islam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jesuschristformuslims.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/La-vida-de-los-ap\u00f3statas-del-Islam-Evangelizar-Musulm\u00e1n-Cor\u00e1n-y-la-Biblia.jpg\",\"datePublished\":\"2018-07-23T13:51:07+00:00\",\"dateModified\":\"2018-10-05T13:59:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#\\\/schema\\\/person\\\/f6120ac59bddfd1d31b3ed5154d08424\"},\"description\":\"La vida de los ap\u00f3statas del Islam en Pakist\u00e1n. Se dice que los ap\u00f3statas del Islam han ganado un billete de ida al infierno. Hasta donde yo s\u00e9, literalment\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/la-vida-de-los-apostatas-del-islam\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/la-vida-de-los-apostatas-del-islam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/la-vida-de-los-apostatas-del-islam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/La-vida-de-los-ap\u00f3statas-del-Islam-Evangelizar-Musulm\u00e1n-Cor\u00e1n-y-la-Biblia.jpg\",\"contentUrl\":\"https:\\\/\\\/jesuschristformuslims.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/La-vida-de-los-ap\u00f3statas-del-Islam-Evangelizar-Musulm\u00e1n-Cor\u00e1n-y-la-Biblia.jpg\",\"width\":1024,\"height\":576,\"caption\":\"La vida de los ap\u00f3statas del Islam | Evangelizar Musulm\u00e1n | Cor\u00e1n y la Biblia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/la-vida-de-los-apostatas-del-islam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La vida de los ap\u00f3statas del Islam\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/\",\"name\":\"Jesus Christ for Muslims\",\"description\":\"Inviting Muslims to the Kingdom of Christ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jesuschristformuslims.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#\\\/schema\\\/person\\\/f6120ac59bddfd1d31b3ed5154d08424\",\"name\":\"David Rothfuss\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g\",\"caption\":\"David Rothfuss\"},\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/author\\\/david-rothfuss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La vida de los ap\u00f3statas del Islam | Evangelizar Musulm\u00e1n | Cor\u00e1n y la Biblia","description":"La vida de los ap\u00f3statas del Islam en Pakist\u00e1n. Se dice que los ap\u00f3statas del Islam han ganado un billete de ida al infierno. Hasta donde yo s\u00e9, literalment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/","og_locale":"es_ES","og_type":"article","og_title":"La vida de los ap\u00f3statas del Islam | Evangelizar Musulm\u00e1n | Cor\u00e1n y la Biblia","og_description":"La vida de los ap\u00f3statas del Islam en Pakist\u00e1n. Se dice que los ap\u00f3statas del Islam han ganado un billete de ida al infierno. Hasta donde yo s\u00e9, literalment","og_url":"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/","og_site_name":"Jesus Christ for Muslims","article_published_time":"2018-07-23T13:51:07+00:00","article_modified_time":"2018-10-05T13:59:21+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2018\/07\/La-vida-de-los-ap\u00f3statas-del-Islam-Evangelizar-Musulm\u00e1n-Cor\u00e1n-y-la-Biblia.jpg","type":"image\/jpeg"}],"author":"David Rothfuss","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David Rothfuss","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/#article","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/"},"author":{"name":"David Rothfuss","@id":"https:\/\/jesuschristformuslims.com\/#\/schema\/person\/f6120ac59bddfd1d31b3ed5154d08424"},"headline":"La vida de los ap\u00f3statas del Islam","datePublished":"2018-07-23T13:51:07+00:00","dateModified":"2018-10-05T13:59:21+00:00","mainEntityOfPage":{"@id":"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/"},"wordCount":509,"commentCount":0,"image":{"@id":"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/#primaryimage"},"thumbnailUrl":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2018\/07\/La-vida-de-los-ap\u00f3statas-del-Islam-Evangelizar-Musulm\u00e1n-Cor\u00e1n-y-la-Biblia.jpg","keywords":["ap\u00f3stata","Ap\u00f3stata Del Islam","Biblia","Cor\u00e1n","pakistan"],"articleSection":["Bienvenida","Blog"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/","url":"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/","name":"La vida de los ap\u00f3statas del Islam | Evangelizar Musulm\u00e1n | Cor\u00e1n y la Biblia","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/#primaryimage"},"image":{"@id":"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/#primaryimage"},"thumbnailUrl":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2018\/07\/La-vida-de-los-ap\u00f3statas-del-Islam-Evangelizar-Musulm\u00e1n-Cor\u00e1n-y-la-Biblia.jpg","datePublished":"2018-07-23T13:51:07+00:00","dateModified":"2018-10-05T13:59:21+00:00","author":{"@id":"https:\/\/jesuschristformuslims.com\/#\/schema\/person\/f6120ac59bddfd1d31b3ed5154d08424"},"description":"La vida de los ap\u00f3statas del Islam en Pakist\u00e1n. Se dice que los ap\u00f3statas del Islam han ganado un billete de ida al infierno. Hasta donde yo s\u00e9, literalment","breadcrumb":{"@id":"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/#primaryimage","url":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2018\/07\/La-vida-de-los-ap\u00f3statas-del-Islam-Evangelizar-Musulm\u00e1n-Cor\u00e1n-y-la-Biblia.jpg","contentUrl":"https:\/\/jesuschristformuslims.com\/wp-content\/uploads\/2018\/07\/La-vida-de-los-ap\u00f3statas-del-Islam-Evangelizar-Musulm\u00e1n-Cor\u00e1n-y-la-Biblia.jpg","width":1024,"height":576,"caption":"La vida de los ap\u00f3statas del Islam | Evangelizar Musulm\u00e1n | Cor\u00e1n y la Biblia"},{"@type":"BreadcrumbList","@id":"https:\/\/jesuschristformuslims.com\/es\/la-vida-de-los-apostatas-del-islam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jesuschristformuslims.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"La vida de los ap\u00f3statas del Islam"}]},{"@type":"WebSite","@id":"https:\/\/jesuschristformuslims.com\/#website","url":"https:\/\/jesuschristformuslims.com\/","name":"Jesus Christ for Muslims","description":"Inviting Muslims to the Kingdom of Christ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jesuschristformuslims.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/jesuschristformuslims.com\/#\/schema\/person\/f6120ac59bddfd1d31b3ed5154d08424","name":"David Rothfuss","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g","caption":"David Rothfuss"},"url":"https:\/\/jesuschristformuslims.com\/es\/author\/david-rothfuss\/"}]}},"_links":{"self":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts\/7478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/comments?post=7478"}],"version-history":[{"count":3,"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts\/7478\/revisions"}],"predecessor-version":[{"id":8572,"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts\/7478\/revisions\/8572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/media\/7479"}],"wp:attachment":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/media?parent=7478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/categories?post=7478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags?post=7478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}