{"id":1025,"count":1,"description":"El Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia (ACNUR, en ingl\u00e9s UNHCR, United Nations High Commissioner for Refugees) es el organismo de las Naciones Unidas encargado de proteger a los refugiados y desplazados por persecuciones o conflictos, y promover soluciones duraderas a su situaci\u00f3n, mediante el reasentamiento voluntario en su pa\u00eds de origen o en el de acogida. Tiene su sede en Ginebra, Suiza, y m\u00e1s de 250 oficinas repartidas por todo el mundo. El derecho al asilo y refugio es contemplado en la Declaraci\u00f3n Universal de Derechos Humanos:\r\n\r\nEl Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia pide acceso para migrantes detenidos en alta mar;\u00a0La Oficina del Alto Comisionado de las Naciones Unidas para los Refugiados (ACNUR) solicit\u00f3 al gobierno de Tailandia que permita el acceso de 126 migrantes que se encuentran en dos embarcaciones custodiadas frente a la costa sur de ese pa\u00eds.\r\n\r\nEl Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia preocupado por repatriaci\u00f3n de laosianos;\u00a0La Oficina del Alto Comisionado de las Naciones Unidas para los Refugiados (ACNUR) le expres\u00f3 al gobierno tailand\u00e9s su preocupaci\u00f3n por el retorno de Tailandia de m\u00e1s de 800 ciudadanos de Laos de la etnia Hmong.\r\n\r\nEl Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia celebra el plan del Gobierno tailand\u00e9s para identificar refugiados;\u00a0El Alto Comisionado de Naciones Unidas para los Refugiados (ACNUR) aplaudi\u00f3 hoy el plan del Gobierno tailand\u00e9s para la creaci\u00f3n de un mecanismo que identifique a inmigrantes indocumentados y refugiados.","link":"https:\/\/jesuschristformuslims.com\/es\/tag\/alto-comisionado-de-las-naciones-unidas-para-los-refugiados-tailandia\/","name":"alto comisionado de las naciones unidas para los refugiados tailandia","slug":"alto-comisionado-de-las-naciones-unidas-para-los-refugiados-tailandia","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia | ACNUR<\/title>\n<meta name=\"description\" content=\"El Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia (ACNUR, en ingl\u00e9s UNHCR, United Nations High Commissioner for Refugees) es el or...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jesuschristformuslims.com\/es\/tag\/alto-comisionado-de-las-naciones-unidas-para-los-refugiados-tailandia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia | ACNUR\" \/>\n<meta property=\"og:description\" content=\"El Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia (ACNUR, en ingl\u00e9s UNHCR, United Nations High Commissioner for Refugees) es el or...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jesuschristformuslims.com\/es\/tag\/alto-comisionado-de-las-naciones-unidas-para-los-refugiados-tailandia\/\" \/>\n<meta property=\"og:site_name\" content=\"Jesus Christ for Muslims\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/alto-comisionado-de-las-naciones-unidas-para-los-refugiados-tailandia\\\/\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/alto-comisionado-de-las-naciones-unidas-para-los-refugiados-tailandia\\\/\",\"name\":\"Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia | ACNUR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\"},\"description\":\"El Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia (ACNUR, en ingl\u00e9s UNHCR, United Nations High Commissioner for Refugees) es el or...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/alto-comisionado-de-las-naciones-unidas-para-los-refugiados-tailandia\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/alto-comisionado-de-las-naciones-unidas-para-los-refugiados-tailandia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"alto comisionado de las naciones unidas para los refugiados tailandia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/\",\"name\":\"Jesus Christ for Muslims\",\"description\":\"Inviting Muslims to the Kingdom of Christ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jesuschristformuslims.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia | ACNUR","description":"El Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia (ACNUR, en ingl\u00e9s UNHCR, United Nations High Commissioner for Refugees) es el or...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jesuschristformuslims.com\/es\/tag\/alto-comisionado-de-las-naciones-unidas-para-los-refugiados-tailandia\/","og_locale":"es_ES","og_type":"article","og_title":"Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia | ACNUR","og_description":"El Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia (ACNUR, en ingl\u00e9s UNHCR, United Nations High Commissioner for Refugees) es el or...","og_url":"https:\/\/jesuschristformuslims.com\/es\/tag\/alto-comisionado-de-las-naciones-unidas-para-los-refugiados-tailandia\/","og_site_name":"Jesus Christ for Muslims","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/alto-comisionado-de-las-naciones-unidas-para-los-refugiados-tailandia\/","url":"https:\/\/jesuschristformuslims.com\/es\/tag\/alto-comisionado-de-las-naciones-unidas-para-los-refugiados-tailandia\/","name":"Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia | ACNUR","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/#website"},"description":"El Alto Comisionado de las Naciones Unidas para los Refugiados Tailandia (ACNUR, en ingl\u00e9s UNHCR, United Nations High Commissioner for Refugees) es el or...","breadcrumb":{"@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/alto-comisionado-de-las-naciones-unidas-para-los-refugiados-tailandia\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/alto-comisionado-de-las-naciones-unidas-para-los-refugiados-tailandia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jesuschristformuslims.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"alto comisionado de las naciones unidas para los refugiados tailandia"}]},{"@type":"WebSite","@id":"https:\/\/jesuschristformuslims.com\/#website","url":"https:\/\/jesuschristformuslims.com\/","name":"Jesus Christ for Muslims","description":"Inviting Muslims to the Kingdom of Christ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jesuschristformuslims.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags\/1025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts?tags=1025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}