{"id":1049,"count":1,"description":"Santificado sea tu nombre: \u00a1Nombre, marca e imagen! En un mundo lleno de nomenclaturas, manipuladores de ficheros y gur\u00fas de mercadeo, hemos llegado a comprender en la realidad actual que hay poder en un \u00a1nombre! Compramos autom\u00f3viles, ropa, comida, computadoras y hasta papel higi\u00e9nico, dej\u00e1ndonos llevar por la marca y el nombre. Le damos importancia a los nombres. Exaltamos y honramos nombres de artistas, pol\u00edticos, presidentes, reyes, deportistas y dem\u00e1s.\r\n\r\nNo obstante, nada es m\u00e1s santo, m\u00e1s sagrado ni debe ser m\u00e1s honrado y respetado que el nombre de nuestro Dios todopoderoso. Jes\u00fas comenz\u00f3 la oraci\u00f3n m\u00e1s poderosa en toda la humanidad declarando: Padre nuestro que est\u00e1s en los cielos, santificado sea tu nombre.\r\n\r\n\u00bfQu\u00e9 significa santificado sea tu nombre? Quiere decir que no hay nada m\u00e1s santo que el nombre de Dios; santo es su nombre. No significa que hacemos santo su nombre, sino que su nombre ya es santo. Isa\u00edas dio testimonio del clamor del seraf\u00edn en Isa\u00edas 6:3 (NVI): \u201cSanto, santo, santo es el Se\u00f1or todopoderoso\u201d.","link":"https:\/\/jesuschristformuslims.com\/es\/tag\/santificado-sea-tu-nombre\/","name":"santificado sea tu Nombre","slug":"santificado-sea-tu-nombre","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santificado sea tu nombre | Evangelizaci\u00f3n al Mundo Isl\u00e1mico | Testimonios Ex Musulmanes<\/title>\n<meta name=\"description\" content=\"Santificado sea tu nombre: \u00a1Nombre, marca e imagen! En un mundo lleno de nomenclaturas, manipuladores de ficheros y gur\u00fas de mercadeo, hemos llegado a co...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jesuschristformuslims.com\/es\/tag\/santificado-sea-tu-nombre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santificado sea tu nombre | Evangelizaci\u00f3n al Mundo Isl\u00e1mico | Testimonios Ex Musulmanes\" \/>\n<meta property=\"og:description\" content=\"Santificado sea tu nombre: \u00a1Nombre, marca e imagen! En un mundo lleno de nomenclaturas, manipuladores de ficheros y gur\u00fas de mercadeo, hemos llegado a co...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jesuschristformuslims.com\/es\/tag\/santificado-sea-tu-nombre\/\" \/>\n<meta property=\"og:site_name\" content=\"Jesus Christ for Muslims\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/santificado-sea-tu-nombre\\\/\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/santificado-sea-tu-nombre\\\/\",\"name\":\"Santificado sea tu nombre | Evangelizaci\u00f3n al Mundo Isl\u00e1mico | Testimonios Ex Musulmanes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\"},\"description\":\"Santificado sea tu nombre: \u00a1Nombre, marca e imagen! En un mundo lleno de nomenclaturas, manipuladores de ficheros y gur\u00fas de mercadeo, hemos llegado a co...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/santificado-sea-tu-nombre\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/santificado-sea-tu-nombre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"santificado sea tu Nombre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/\",\"name\":\"Jesus Christ for Muslims\",\"description\":\"Inviting Muslims to the Kingdom of Christ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jesuschristformuslims.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santificado sea tu nombre | Evangelizaci\u00f3n al Mundo Isl\u00e1mico | Testimonios Ex Musulmanes","description":"Santificado sea tu nombre: \u00a1Nombre, marca e imagen! En un mundo lleno de nomenclaturas, manipuladores de ficheros y gur\u00fas de mercadeo, hemos llegado a co...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jesuschristformuslims.com\/es\/tag\/santificado-sea-tu-nombre\/","og_locale":"es_ES","og_type":"article","og_title":"Santificado sea tu nombre | Evangelizaci\u00f3n al Mundo Isl\u00e1mico | Testimonios Ex Musulmanes","og_description":"Santificado sea tu nombre: \u00a1Nombre, marca e imagen! En un mundo lleno de nomenclaturas, manipuladores de ficheros y gur\u00fas de mercadeo, hemos llegado a co...","og_url":"https:\/\/jesuschristformuslims.com\/es\/tag\/santificado-sea-tu-nombre\/","og_site_name":"Jesus Christ for Muslims","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/santificado-sea-tu-nombre\/","url":"https:\/\/jesuschristformuslims.com\/es\/tag\/santificado-sea-tu-nombre\/","name":"Santificado sea tu nombre | Evangelizaci\u00f3n al Mundo Isl\u00e1mico | Testimonios Ex Musulmanes","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/#website"},"description":"Santificado sea tu nombre: \u00a1Nombre, marca e imagen! En un mundo lleno de nomenclaturas, manipuladores de ficheros y gur\u00fas de mercadeo, hemos llegado a co...","breadcrumb":{"@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/santificado-sea-tu-nombre\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/santificado-sea-tu-nombre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jesuschristformuslims.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"santificado sea tu Nombre"}]},{"@type":"WebSite","@id":"https:\/\/jesuschristformuslims.com\/#website","url":"https:\/\/jesuschristformuslims.com\/","name":"Jesus Christ for Muslims","description":"Inviting Muslims to the Kingdom of Christ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jesuschristformuslims.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags\/1049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts?tags=1049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}