{"id":1313,"count":1,"description":"En esto consiste el amor: no en que nosotros hayamos amado a Dios, sino en que \u00e9l nos am\u00f3 y envi\u00f3 a nuestro \"amado Se\u00f1or Jesucristo\" para que fuera ofrecido como sacrificio por el perd\u00f3n de nuestros pecados. 1 Juan 4:10\r\n\r\nQuien, siendo por naturaleza Dios, no consider\u00f3 el ser igual a Dios como algo a qu\u00e9 aferrarse. Por el contrario, se rebaj\u00f3 voluntariamente, tomando la naturaleza de siervo y haci\u00e9ndose semejante a los seres humanos. Y al manifestarse como hombre, se humill\u00f3 a s\u00ed mismo y se hizo obediente hasta la muerte, \u00a1y muerte de cruz!. Filipenses 2:6-8\r\n\r\nHablando del Se\u00f1or Jesucristo, el ap\u00f3stol Pablo dice lo siguiente en Colosenses 2:3 \u201cen quien est\u00e1n escondidos todos los tesoros de la sabidur\u00eda y del conocimiento\u201d\r\n\r\nComo bien saben, ustedes fueron rescatados de la vida absurda que heredaron de sus antepasados. El precio de su rescate no se pag\u00f3 con cosas perecederas, como el oro o la plata, sino con la preciosa sangre de Cristo, como de un cordero sin mancha y sin defecto.\r\n1 Pedro 1:18-19","link":"https:\/\/jesuschristformuslims.com\/es\/tag\/amado-senor-jesucristo\/","name":"amado Se\u00f1or Jesucristo","slug":"amado-senor-jesucristo","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amado Se\u00f1or Jesucristo | Salvador | Cordero Inmolado | Rey de Reyes<\/title>\n<meta name=\"description\" content=\"En esto consiste el amor: no en que nosotros hayamos amado a Dios, sino en que \u00e9l nos am\u00f3 y envi\u00f3 a nuestro &quot;amado Se\u00f1or Jesucristo&quot; para que fuera ofrec...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jesuschristformuslims.com\/es\/tag\/amado-senor-jesucristo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amado Se\u00f1or Jesucristo | Salvador | Cordero Inmolado | Rey de Reyes\" \/>\n<meta property=\"og:description\" content=\"En esto consiste el amor: no en que nosotros hayamos amado a Dios, sino en que \u00e9l nos am\u00f3 y envi\u00f3 a nuestro &quot;amado Se\u00f1or Jesucristo&quot; para que fuera ofrec...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jesuschristformuslims.com\/es\/tag\/amado-senor-jesucristo\/\" \/>\n<meta property=\"og:site_name\" content=\"Jesus Christ for Muslims\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/amado-senor-jesucristo\\\/\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/amado-senor-jesucristo\\\/\",\"name\":\"Amado Se\u00f1or Jesucristo | Salvador | Cordero Inmolado | Rey de Reyes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\"},\"description\":\"En esto consiste el amor: no en que nosotros hayamos amado a Dios, sino en que \u00e9l nos am\u00f3 y envi\u00f3 a nuestro \\\"amado Se\u00f1or Jesucristo\\\" para que fuera ofrec...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/amado-senor-jesucristo\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/amado-senor-jesucristo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"amado Se\u00f1or Jesucristo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/\",\"name\":\"Jesus Christ for Muslims\",\"description\":\"Inviting Muslims to the Kingdom of Christ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jesuschristformuslims.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amado Se\u00f1or Jesucristo | Salvador | Cordero Inmolado | Rey de Reyes","description":"En esto consiste el amor: no en que nosotros hayamos amado a Dios, sino en que \u00e9l nos am\u00f3 y envi\u00f3 a nuestro \"amado Se\u00f1or Jesucristo\" para que fuera ofrec...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jesuschristformuslims.com\/es\/tag\/amado-senor-jesucristo\/","og_locale":"es_ES","og_type":"article","og_title":"Amado Se\u00f1or Jesucristo | Salvador | Cordero Inmolado | Rey de Reyes","og_description":"En esto consiste el amor: no en que nosotros hayamos amado a Dios, sino en que \u00e9l nos am\u00f3 y envi\u00f3 a nuestro \"amado Se\u00f1or Jesucristo\" para que fuera ofrec...","og_url":"https:\/\/jesuschristformuslims.com\/es\/tag\/amado-senor-jesucristo\/","og_site_name":"Jesus Christ for Muslims","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/amado-senor-jesucristo\/","url":"https:\/\/jesuschristformuslims.com\/es\/tag\/amado-senor-jesucristo\/","name":"Amado Se\u00f1or Jesucristo | Salvador | Cordero Inmolado | Rey de Reyes","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/#website"},"description":"En esto consiste el amor: no en que nosotros hayamos amado a Dios, sino en que \u00e9l nos am\u00f3 y envi\u00f3 a nuestro \"amado Se\u00f1or Jesucristo\" para que fuera ofrec...","breadcrumb":{"@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/amado-senor-jesucristo\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/amado-senor-jesucristo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jesuschristformuslims.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"amado Se\u00f1or Jesucristo"}]},{"@type":"WebSite","@id":"https:\/\/jesuschristformuslims.com\/#website","url":"https:\/\/jesuschristformuslims.com\/","name":"Jesus Christ for Muslims","description":"Inviting Muslims to the Kingdom of Christ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jesuschristformuslims.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags\/1313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts?tags=1313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}