{"id":3578,"count":1,"description":"Vers\u00edculos b\u00edblicos sobre el amor del Se\u00f1or\r\n\r\nEl m\u00e1s grande mandamiento es amar a Dios con todo nuestro coraz\u00f3n, con toda nuestra alma y con toda nuestra fuerza. Nosotros amamos a Dios y \u00c9l nos ama a nosotros.\r\n\r\nNosotros le amamos a \u00e9l, porque \u00e9l nos am\u00f3 primero. (1 Juan 4:19), Alabad a Jehov\u00e1, porque \u00e9l es bueno, Porque para siempre es su misericordia. (Salmos 136:1), Mas t\u00fa, Se\u00f1or, Dios misericordioso y clemente, lento para la ira, y grande en misericordia y verdad (Salmos 86:15)\r\n\r\nPorque de tal manera am\u00f3 Dios al mundo, que ha dado a su Hijo unig\u00e9nito, para que todo aquel que en \u00e9l cree, no se pierda, mas tenga vida eterna. (Juan 3:16)\r\n\r\nEl que no ama, no ha conocido a Dios; porque Dios es amor. En esto se mostr\u00f3 el amor de Dios para con nosotros, en que Dios envi\u00f3 a su Hijo unig\u00e9nito al mundo, para que vivamos por \u00e9l. En esto consiste el amor: no en que nosotros hayamos amado a Dios, sino en que \u00e9l nos am\u00f3 a nosotros, y envi\u00f3 a su Hijo en propiciaci\u00f3n por nuestros pecados. (1 Juan 4:8-10)","link":"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-del-senor\/","name":"amor del Se\u00f1or","slug":"amor-del-senor","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amor del Se\u00f1or | Gran Mandamiento | Amor \u00c1gape | Dios es Amor<\/title>\n<meta name=\"description\" content=\"Vers\u00edculos b\u00edblicos sobre el amor del Se\u00f1or: El m\u00e1s grande mandamiento es amar a Dios con todo nuestro coraz\u00f3n, con toda nuestra alma y con toda nuestra....\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-del-senor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amor del Se\u00f1or | Gran Mandamiento | Amor \u00c1gape | Dios es Amor\" \/>\n<meta property=\"og:description\" content=\"Vers\u00edculos b\u00edblicos sobre el amor del Se\u00f1or: El m\u00e1s grande mandamiento es amar a Dios con todo nuestro coraz\u00f3n, con toda nuestra alma y con toda nuestra....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-del-senor\/\" \/>\n<meta property=\"og:site_name\" content=\"Jesus Christ for Muslims\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/amor-del-senor\\\/\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/amor-del-senor\\\/\",\"name\":\"Amor del Se\u00f1or | Gran Mandamiento | Amor \u00c1gape | Dios es Amor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\"},\"description\":\"Vers\u00edculos b\u00edblicos sobre el amor del Se\u00f1or: El m\u00e1s grande mandamiento es amar a Dios con todo nuestro coraz\u00f3n, con toda nuestra alma y con toda nuestra....\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/amor-del-senor\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/amor-del-senor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"amor del Se\u00f1or\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/\",\"name\":\"Jesus Christ for Muslims\",\"description\":\"Inviting Muslims to the Kingdom of Christ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jesuschristformuslims.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amor del Se\u00f1or | Gran Mandamiento | Amor \u00c1gape | Dios es Amor","description":"Vers\u00edculos b\u00edblicos sobre el amor del Se\u00f1or: El m\u00e1s grande mandamiento es amar a Dios con todo nuestro coraz\u00f3n, con toda nuestra alma y con toda nuestra....","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-del-senor\/","og_locale":"es_ES","og_type":"article","og_title":"Amor del Se\u00f1or | Gran Mandamiento | Amor \u00c1gape | Dios es Amor","og_description":"Vers\u00edculos b\u00edblicos sobre el amor del Se\u00f1or: El m\u00e1s grande mandamiento es amar a Dios con todo nuestro coraz\u00f3n, con toda nuestra alma y con toda nuestra....","og_url":"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-del-senor\/","og_site_name":"Jesus Christ for Muslims","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-del-senor\/","url":"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-del-senor\/","name":"Amor del Se\u00f1or | Gran Mandamiento | Amor \u00c1gape | Dios es Amor","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/#website"},"description":"Vers\u00edculos b\u00edblicos sobre el amor del Se\u00f1or: El m\u00e1s grande mandamiento es amar a Dios con todo nuestro coraz\u00f3n, con toda nuestra alma y con toda nuestra....","breadcrumb":{"@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-del-senor\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-del-senor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jesuschristformuslims.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"amor del Se\u00f1or"}]},{"@type":"WebSite","@id":"https:\/\/jesuschristformuslims.com\/#website","url":"https:\/\/jesuschristformuslims.com\/","name":"Jesus Christ for Muslims","description":"Inviting Muslims to the Kingdom of Christ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jesuschristformuslims.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags\/3578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts?tags=3578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}