{"id":5882,"count":1,"description":"Fariseos -\r\n\r\n\u201cMaulvi\u201d es un t\u00edtulo religioso isl\u00e1mico dado a eruditos religiosos musulmanes. Igual que los pastores en el cristianismo, los maulvis son los maestros religiosos para los musulmanes. Pero, \u00bfcu\u00e1n religiosos son en realidad?\r\n\r\nEn Pakist\u00e1n, estos maulvis son conocidos por violar a ni\u00f1as, sodomizar ni\u00f1os, golpear brutalmente a sus estudiantes y promover agresiones, disturbios, confusi\u00f3n, racismo y terrorismo en sus sermones, pero aparte de eso son muy piadosos.\r\n\r\nLos maulvis completan su educaci\u00f3n principalmente en las madrassas (escuelas isl\u00e1micas), ya que no tienen la capacidad de absorberse en el mercado laboral. Y como no tienen conocimiento de ninguna otra habilidad, en su mayor\u00eda consiguen trabajos en las mezquitas. Utilic\u00e9 la palabra \u201cEmpleos\u201d porque nunca es la ense\u00f1anza religiosa y la paz lo que promueven sino que siempre buscan formas de sacar dinero de los bolsillos de quienes viven en la comunidad que rodea la mezquita. Venden el nombre de su Al\u00e1 y crean l\u00edmites imaginarios entre los musulmanes. No solo entre los musulmanes, sino que tambi\u00e9n instigan a los musulmanes contra los no musulmanes.\r\n\r\nMuchos cristianos en Pakist\u00e1n han sido asesinados por musulmanes solo porque un tal Maulvis hab\u00eda dado una fatwa declarando que el cristiano en cuesti\u00f3n era un infiel o blasfemo y por lo tanto no ten\u00eda derecho a vivir. Las verdaderas causas de tal persecuci\u00f3n extrema en Pakist\u00e1n contra los no musulmanes son los sermones que promueven el odio de estos Maulvis. Nunca llegan a la luz ellos mismos, sino que proclaman audazmente c\u00f3mo un asesino no musulm\u00e1n debe ser asesinado, solo porque seg\u00fan Maulvis \u201cest\u00e1n caminando por el camino equivocado\u201d.\r\n\r\nAdem\u00e1s, no se debe ignorar que la mayor\u00eda de las organizaciones terroristas que han sido responsables de matar miles de vidas en masacres y ataques suicidas en todo el mundo no fueron iniciadas por ninguno de los Maulvi.\r\n\r\nAl igual que los fariseos, estos Maulvis act\u00faan como los seres m\u00e1s puros de la Tierra, pero a la vez promueven tanto odio e ira contra otras religiones que resulta imposible para esos grupos \u00e9tnicos vivir en Pakist\u00e1n. Incluso los propios musulmanes audazmente afirman que los Maulvis son en su mayor\u00eda responsables de desviar el verdadero mensaje de su religi\u00f3n. Pero la pregunta es \u00bfpor qu\u00e9 se les da tanta importancia? \u00bfPor qu\u00e9 se toma su comando como el veredicto final? \u00bfEsto no les da el mismo estatus que Dios? \u00bfQui\u00e9nes son para declarar a alguien infiel o digno de muerte? Antes de juzgar a otra persona, \u00bfno deber\u00edan primero juzgar y corregir a su propio personaje? \u00bfO es lo que hacen, el \u201ccamino correcto\u201d deber\u00eda ser seguido por todos los musulmanes?\r\n\r\nLos musulmanes y el islam deben volver a pensar y redise\u00f1ar millones de cosas que est\u00e1n da\u00f1ando gravemente su reputaci\u00f3n y uno de esos asuntos m\u00e1s importantes es volver impotentes a estos maulvis que est\u00e1n destruyendo la paz y la armon\u00eda religiosa en pa\u00edses como Pakist\u00e1n.\r\n\r\nArif Masih\r\n\r\nGujranwala \u2013 Pakist\u00e1n","link":"https:\/\/jesuschristformuslims.com\/es\/tag\/fariseos\/","name":"fariseos","slug":"fariseos","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fariseos | Del Islam al Cristianismo | Conversi\u00f3n del Islam al Cristianismo<\/title>\n<meta name=\"description\" content=\"Fariseos - \u201cMaulvi\u201d es un t\u00edtulo religioso isl\u00e1mico dado a eruditos religiosos musulmanes. Igual que los pastores en el cristianismo, los maulvis son los ma\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jesuschristformuslims.com\/es\/tag\/fariseos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fariseos | Del Islam al Cristianismo | Conversi\u00f3n del Islam al Cristianismo\" \/>\n<meta property=\"og:description\" content=\"Fariseos - \u201cMaulvi\u201d es un t\u00edtulo religioso isl\u00e1mico dado a eruditos religiosos musulmanes. Igual que los pastores en el cristianismo, los maulvis son los ma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jesuschristformuslims.com\/es\/tag\/fariseos\/\" \/>\n<meta property=\"og:site_name\" content=\"Jesus Christ for Muslims\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/fariseos\\\/\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/fariseos\\\/\",\"name\":\"Fariseos | Del Islam al Cristianismo | Conversi\u00f3n del Islam al Cristianismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\"},\"description\":\"Fariseos - \u201cMaulvi\u201d es un t\u00edtulo religioso isl\u00e1mico dado a eruditos religiosos musulmanes. Igual que los pastores en el cristianismo, los maulvis son los ma\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/fariseos\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/fariseos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"fariseos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/\",\"name\":\"Jesus Christ for Muslims\",\"description\":\"Inviting Muslims to the Kingdom of Christ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jesuschristformuslims.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fariseos | Del Islam al Cristianismo | Conversi\u00f3n del Islam al Cristianismo","description":"Fariseos - \u201cMaulvi\u201d es un t\u00edtulo religioso isl\u00e1mico dado a eruditos religiosos musulmanes. Igual que los pastores en el cristianismo, los maulvis son los ma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jesuschristformuslims.com\/es\/tag\/fariseos\/","og_locale":"es_ES","og_type":"article","og_title":"Fariseos | Del Islam al Cristianismo | Conversi\u00f3n del Islam al Cristianismo","og_description":"Fariseos - \u201cMaulvi\u201d es un t\u00edtulo religioso isl\u00e1mico dado a eruditos religiosos musulmanes. Igual que los pastores en el cristianismo, los maulvis son los ma","og_url":"https:\/\/jesuschristformuslims.com\/es\/tag\/fariseos\/","og_site_name":"Jesus Christ for Muslims","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/fariseos\/","url":"https:\/\/jesuschristformuslims.com\/es\/tag\/fariseos\/","name":"Fariseos | Del Islam al Cristianismo | Conversi\u00f3n del Islam al Cristianismo","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/#website"},"description":"Fariseos - \u201cMaulvi\u201d es un t\u00edtulo religioso isl\u00e1mico dado a eruditos religiosos musulmanes. Igual que los pastores en el cristianismo, los maulvis son los ma","breadcrumb":{"@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/fariseos\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/fariseos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jesuschristformuslims.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"fariseos"}]},{"@type":"WebSite","@id":"https:\/\/jesuschristformuslims.com\/#website","url":"https:\/\/jesuschristformuslims.com\/","name":"Jesus Christ for Muslims","description":"Inviting Muslims to the Kingdom of Christ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jesuschristformuslims.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags\/5882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts?tags=5882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}