{"id":5961,"count":1,"description":"Hijos de Anarquia -\r\n\r\nEl billete al\u00a0cielo, mucha gente piensa que todas las religiones agradan a Dios, pero lo Biblia no dice eso. No es suficiente decir que somos cristianos. Jes\u00fas dijo: \u201cNo todo el que me diga \u2018Se\u00f1or, Se\u00f1or\u2019, entrar\u00e1 en el Reino de los Cielos, pero todo aquel que haga la voluntad del padre, heredar\u00e1 el Reino de los cielos\u201d. Para obtener la aprobaci\u00f3n de Dios debemos conocer los requisitos de Dios, que es lo que quiere de nosotros. Jes\u00fas llam\u00f3 a todos aquellos que no hacen la voluntad de Dios \u201cHijos de Anarquia\u201d.\u00a0<strong>Mateo 7:21-23\u00a0<\/strong>De la misma forma en que el dinero falso no tiene valor, de igual manera la religi\u00f3n falsa no tiene peso. Peor a\u00fan, esta religi\u00f3n puede resultar ser da\u00f1ina y devastadora. El cristianismo es un estilo de vida, no un t\u00edtulo o estatus.\r\n\r\nEste vers\u00edculo est\u00e1 hablando sobre de los l\u00edderes religiosos hip\u00f3critas, de los que tanto hablaba Jes\u00fas. Muchos afirman conocer a Jes\u00fas y a su padre Dios, pero en realidad, piensan cosas muy contrarias a la voluntad de Dios. Muchas de las iglesias de hoy en d\u00eda son hip\u00f3critas, viven una vida de hipocres\u00eda, de necedad. Pretenden ser una iglesia que profesa el cristianismo, pero hace y piensan cosas que no est\u00e1n permitidas en la Biblia. L\u00edderes, pastores y personas de alto cargo en la Iglesia ganan dinero por la Palabra de Dios.\r\n\r\n<strong>Mateo 10:8\u00a0<\/strong>\u2013 Jes\u00fas les dir\u00e1, \u201c\u2018No os conozco\u2019, apartaos de m\u00ed, hacedores de maldad.\u201d Es s\u00faper importante no estar en esta situaci\u00f3n, nuestra relaci\u00f3n personal con Dios no debe ser as\u00ed.\r\n\r\nMuchos creen en Jes\u00fas, dicen creer, pero no hacen lo que la palabra ordena. La Biblia dice que no suficiente creer en Jes\u00fas, tambi\u00e9n hay que hacer lo que \u00c9l nos manda. Los l\u00edderes religiosos, escribas y muchos cristianos dicen con su boca haber expulsado fuera demonios en el nombre del Jes\u00fas, pero lo que sucede es que nunca le conocieron en su vida personal. Poseen motivaciones err\u00f3neas y por lo tanto ense\u00f1an falsa doctrina a la gente. Jes\u00fas se dirigi\u00f3 a todos y dijo, aquellos que quieran seguir mis pasos, no necesitan una profesi\u00f3n de fe para entrar en el cielo, solo el compromiso de vivir una vida directamente conectada con Dios, relaci\u00f3n activa y continua, una vida llena de amor, compasi\u00f3n y perd\u00f3n. No es necesario ser religiosos para poder hacer lo que Dios nos dice. Solo es un estilo de vida, sencillo, que Jes\u00fas","link":"https:\/\/jesuschristformuslims.com\/es\/tag\/hijos-de-anarquia\/","name":"Hijos de Anarquia","slug":"hijos-de-anarquia","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hijos de Anarquia | Mahoma y Jesucristo | Ex musulmanes<\/title>\n<meta name=\"description\" content=\"Hijos de Anarquia - El billete al cielo, mucha gente piensa que todas las religiones agradan a Dios, pero lo Biblia no dice eso. No es suficiente decir que\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jesuschristformuslims.com\/es\/tag\/hijos-de-anarquia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hijos de Anarquia | Mahoma y Jesucristo | Ex musulmanes\" \/>\n<meta property=\"og:description\" content=\"Hijos de Anarquia - El billete al cielo, mucha gente piensa que todas las religiones agradan a Dios, pero lo Biblia no dice eso. No es suficiente decir que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jesuschristformuslims.com\/es\/tag\/hijos-de-anarquia\/\" \/>\n<meta property=\"og:site_name\" content=\"Jesus Christ for Muslims\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/hijos-de-anarquia\\\/\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/hijos-de-anarquia\\\/\",\"name\":\"Hijos de Anarquia | Mahoma y Jesucristo | Ex musulmanes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\"},\"description\":\"Hijos de Anarquia - El billete al cielo, mucha gente piensa que todas las religiones agradan a Dios, pero lo Biblia no dice eso. No es suficiente decir que\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/hijos-de-anarquia\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/hijos-de-anarquia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hijos de Anarquia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/\",\"name\":\"Jesus Christ for Muslims\",\"description\":\"Inviting Muslims to the Kingdom of Christ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jesuschristformuslims.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hijos de Anarquia | Mahoma y Jesucristo | Ex musulmanes","description":"Hijos de Anarquia - El billete al cielo, mucha gente piensa que todas las religiones agradan a Dios, pero lo Biblia no dice eso. No es suficiente decir que","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jesuschristformuslims.com\/es\/tag\/hijos-de-anarquia\/","og_locale":"es_ES","og_type":"article","og_title":"Hijos de Anarquia | Mahoma y Jesucristo | Ex musulmanes","og_description":"Hijos de Anarquia - El billete al cielo, mucha gente piensa que todas las religiones agradan a Dios, pero lo Biblia no dice eso. No es suficiente decir que","og_url":"https:\/\/jesuschristformuslims.com\/es\/tag\/hijos-de-anarquia\/","og_site_name":"Jesus Christ for Muslims","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/hijos-de-anarquia\/","url":"https:\/\/jesuschristformuslims.com\/es\/tag\/hijos-de-anarquia\/","name":"Hijos de Anarquia | Mahoma y Jesucristo | Ex musulmanes","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/#website"},"description":"Hijos de Anarquia - El billete al cielo, mucha gente piensa que todas las religiones agradan a Dios, pero lo Biblia no dice eso. No es suficiente decir que","breadcrumb":{"@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/hijos-de-anarquia\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/hijos-de-anarquia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jesuschristformuslims.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Hijos de Anarquia"}]},{"@type":"WebSite","@id":"https:\/\/jesuschristformuslims.com\/#website","url":"https:\/\/jesuschristformuslims.com\/","name":"Jesus Christ for Muslims","description":"Inviting Muslims to the Kingdom of Christ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jesuschristformuslims.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags\/5961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts?tags=5961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}