{"id":6107,"count":1,"description":"No ansiedad -\r\n\r\n<strong>Isa\u00edas 41:10<\/strong>\u00a0\u2013 No temas, porque yo estoy contigo; no te desanimes, porque yo soy tu Dios. Te fortalecer\u00e9 y te ayudar\u00e9; Te defender\u00e9 con mi diestra mano derecha.\r\n\r\nDios es omnipresente. Esta cualidad es una parte esencial de su Ser como el eterno Dios que llena todo el tiempo y el espacio. Pero hay una gran diferencia en Dios como Dios presente en todas partes y Dios que est\u00e1 contigo. Es cierto que Dios conquistar\u00e1 tus ansiedades y te consolar\u00e1 en tu soledad. \u00c9l prometi\u00f3: \u2013 \u2018\u2019He aqu\u00ed, estoy contigo siempre\u2019\u2019. Con tales promesas, \u00bfpor qu\u00e9 nos vemos tan a menudo en la vida como si estuvi\u00e9ramos solos?\r\n\r\nClaro, hay momentos en que enfrentamos dificultades y nos sentimos solos. Como cuando los amigos se han ido y no puedes encontrar ayuda en un hermano o hermana. Pero la ausencia de un compa\u00f1ero \u2018\u2019mundano\u2019\u2019 no te deja sin esperanza o ayuda. Porque incluso cuando caminas por valles de sombra de muerte, Dios est\u00e1 contigo para protegerte, fortalecerte y cumplir sus buenos prop\u00f3sitos a trav\u00e9s de ti. Nunca est\u00e1s realmente solo. No cargues con el peso de la soledad dise\u00f1ada por ti mismo, porque al hacerlo, seguir\u00e1s temiendo y colapsandote bajo el peso de tus aflicciones.\r\n\r\nMis hermanos y hermanas en Cristo, debemos descansar en la realidad de la presencia de Dios y no temer. Cuando buscamos Su comuni\u00f3n, \u00c9l nunca nos dejar\u00e1, nunca nos sentiremos solos en tiempo de problemas. El tiempo de dificultad vendr\u00e1, pero el Se\u00f1or nos fortalecer\u00e1 para tratar con ellos y atravesarlos con Su Gracia. Cuando Dios est\u00e1 con su pueblo, entonces, como cristiano, puedo asegurarle que usted est\u00e1 con nosotros. Nosotros, siendo cristianos, no debemos temer, ya que sus promesas con verdaderas y \u00c9l permanece a nuestro lado. As\u00ed pues, si el Se\u00f1or est\u00e1 con nosotros para defendernos, y tenemos la promesa de la perseverancia, \u00bfqui\u00e9n podr\u00e1 oponerse a nosotros? La presencia de Dios el Padre te otorgar\u00e1 descanso y esperanza en medio de todas las cosas que generan temor en los corazones de los hombres y mujeres.\r\n\r\nQue Dios nos ayude y nos gu\u00ede para caminar en su camino y vivir en promesas. Am\u00e9n.","link":"https:\/\/jesuschristformuslims.com\/es\/tag\/no-ansiedad\/","name":"no ansiedad","slug":"no-ansiedad","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No ansiedad | Jesucristo en el Cor\u00e1n | Musulmanes y cristianos<\/title>\n<meta name=\"description\" content=\"No ansiedad - Isa\u00edas 41:10 \u2013 No temas, porque yo estoy contigo; no te desanimes, porque yo soy tu Dios. Te fortalecer\u00e9 y te ayudar\u00e9; Te defender\u00e9 con mi die\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jesuschristformuslims.com\/es\/tag\/no-ansiedad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No ansiedad | Jesucristo en el Cor\u00e1n | Musulmanes y cristianos\" \/>\n<meta property=\"og:description\" content=\"No ansiedad - Isa\u00edas 41:10 \u2013 No temas, porque yo estoy contigo; no te desanimes, porque yo soy tu Dios. Te fortalecer\u00e9 y te ayudar\u00e9; Te defender\u00e9 con mi die\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jesuschristformuslims.com\/es\/tag\/no-ansiedad\/\" \/>\n<meta property=\"og:site_name\" content=\"Jesus Christ for Muslims\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/no-ansiedad\\\/\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/no-ansiedad\\\/\",\"name\":\"No ansiedad | Jesucristo en el Cor\u00e1n | Musulmanes y cristianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\"},\"description\":\"No ansiedad - Isa\u00edas 41:10 \u2013 No temas, porque yo estoy contigo; no te desanimes, porque yo soy tu Dios. Te fortalecer\u00e9 y te ayudar\u00e9; Te defender\u00e9 con mi die\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/no-ansiedad\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/no-ansiedad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"no ansiedad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/\",\"name\":\"Jesus Christ for Muslims\",\"description\":\"Inviting Muslims to the Kingdom of Christ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jesuschristformuslims.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No ansiedad | Jesucristo en el Cor\u00e1n | Musulmanes y cristianos","description":"No ansiedad - Isa\u00edas 41:10 \u2013 No temas, porque yo estoy contigo; no te desanimes, porque yo soy tu Dios. Te fortalecer\u00e9 y te ayudar\u00e9; Te defender\u00e9 con mi die","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jesuschristformuslims.com\/es\/tag\/no-ansiedad\/","og_locale":"es_ES","og_type":"article","og_title":"No ansiedad | Jesucristo en el Cor\u00e1n | Musulmanes y cristianos","og_description":"No ansiedad - Isa\u00edas 41:10 \u2013 No temas, porque yo estoy contigo; no te desanimes, porque yo soy tu Dios. Te fortalecer\u00e9 y te ayudar\u00e9; Te defender\u00e9 con mi die","og_url":"https:\/\/jesuschristformuslims.com\/es\/tag\/no-ansiedad\/","og_site_name":"Jesus Christ for Muslims","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/no-ansiedad\/","url":"https:\/\/jesuschristformuslims.com\/es\/tag\/no-ansiedad\/","name":"No ansiedad | Jesucristo en el Cor\u00e1n | Musulmanes y cristianos","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/#website"},"description":"No ansiedad - Isa\u00edas 41:10 \u2013 No temas, porque yo estoy contigo; no te desanimes, porque yo soy tu Dios. Te fortalecer\u00e9 y te ayudar\u00e9; Te defender\u00e9 con mi die","breadcrumb":{"@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/no-ansiedad\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/no-ansiedad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jesuschristformuslims.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"no ansiedad"}]},{"@type":"WebSite","@id":"https:\/\/jesuschristformuslims.com\/#website","url":"https:\/\/jesuschristformuslims.com\/","name":"Jesus Christ for Muslims","description":"Inviting Muslims to the Kingdom of Christ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jesuschristformuslims.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags\/6107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts?tags=6107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}