{"id":6562,"count":1,"description":"Amor todo lo puede -\r\n\r\nEl Cristianismo, el concepto de amor y perd\u00f3n, en muchas ocasiones se pone a prueba cuando los extremistas abrazan la inmundicia al extender sus l\u00edmites a niveles imposibles. Violar ni\u00f1os cristianos de tan solo 6 a\u00f1os, crucificarlos para humillaci\u00f3n, decapitar a las mujeres y mostrar su cabeza no es suficiente violencia. Es como si lo hicieran a prop\u00f3sito para poner a prueba nuestro perd\u00f3n, vienen y preguntan, que \u201c\u00bfTodav\u00eda puedes perdonarnos?\u201d\r\n\r\nLos extremistas cometen cr\u00edmenes tan horribles y espeluznantes que a cualquier le pondr\u00eda enfermo del est\u00f3mago. Es verdad, toda acci\u00f3n tiene una reacci\u00f3n; mayor es la acci\u00f3n, mayor ser\u00e1 la reacci\u00f3n. \u00bfQu\u00e9 reacci\u00f3n podr\u00eda esperarse de los cristianos que son humillados de la peor forma posible en p\u00fablico? \u00bfOdio? \u00bfVenganza? \u00bfUn deseo de que les pase lo mismo o peor? La respuesta correcta es la menos esperada: el perd\u00f3n, el amor y la oraci\u00f3n. No importa cu\u00e1n mal los atribule, lo \u00fanico que quieren darles a sus enemigos es amor, perd\u00f3n y buenos deseos.\r\n\r\nEl mundo, olvida que son humanos y da por hecho muchas cosas, la bondad por ejemplo. Los cristianos son pisoteados en nombre de la persecuci\u00f3n \u00a0profetizado esta en las escrituras y se les dice que guarden silencio tomando el nombre de Dios que \u00c9l lo est\u00e1 probando. Se considera que la voluntad de Dios es que sufran persecuci\u00f3n cuando se olvidan de su propia dignidad y caen a niveles que pueden describirse como inhumanos.\r\n\r\nCristo vino al mundo en el momento de peor castigo y sufrimiento para los blasfemos, a ellos se les dar\u00eda la muerte m\u00e1s horrible. Si \u00c9l lo hubiera preferido pod\u00eda haber elegido otro momento de la historia para venir, cuando morir, es menos doloroso y r\u00e1pido, pero \u00c9l quiso sufrir los peores dolores y padecer el mayor sufrimiento. \u00bfPor qu\u00e9 fue as\u00ed? Fue porque Cristo sab\u00eda la persecuci\u00f3n que se avecinaba. \u00c9l estableci\u00f3 el claro ejemplo a seguir cuando tus enemigos te hacen mal, perdonar a los que les hacen padecer sufrimiento. El perd\u00f3n y el amor describen el cristianismo y as\u00ed debemos ser nosotros, los seguidores de Cristo.","link":"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-todo-lo-puede\/","name":"Amor todo lo puede","slug":"amor-todo-lo-puede","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amor todo lo puede | Musulmanes y Cristianos | Evangelizaci\u00f3n al Mundo Isl\u00e1mico<\/title>\n<meta name=\"description\" content=\"Amor todo lo puede - El Cristianismo, el concepto de amor y perd\u00f3n, en muchas ocasiones se pone a prueba cuando los extremistas abrazan la inmundicia al ext\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-todo-lo-puede\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amor todo lo puede | Musulmanes y Cristianos | Evangelizaci\u00f3n al Mundo Isl\u00e1mico\" \/>\n<meta property=\"og:description\" content=\"Amor todo lo puede - El Cristianismo, el concepto de amor y perd\u00f3n, en muchas ocasiones se pone a prueba cuando los extremistas abrazan la inmundicia al ext\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-todo-lo-puede\/\" \/>\n<meta property=\"og:site_name\" content=\"Jesus Christ for Muslims\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/amor-todo-lo-puede\\\/\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/amor-todo-lo-puede\\\/\",\"name\":\"Amor todo lo puede | Musulmanes y Cristianos | Evangelizaci\u00f3n al Mundo Isl\u00e1mico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\"},\"description\":\"Amor todo lo puede - El Cristianismo, el concepto de amor y perd\u00f3n, en muchas ocasiones se pone a prueba cuando los extremistas abrazan la inmundicia al ext\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/amor-todo-lo-puede\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/amor-todo-lo-puede\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amor todo lo puede\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/\",\"name\":\"Jesus Christ for Muslims\",\"description\":\"Inviting Muslims to the Kingdom of Christ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jesuschristformuslims.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amor todo lo puede | Musulmanes y Cristianos | Evangelizaci\u00f3n al Mundo Isl\u00e1mico","description":"Amor todo lo puede - El Cristianismo, el concepto de amor y perd\u00f3n, en muchas ocasiones se pone a prueba cuando los extremistas abrazan la inmundicia al ext","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-todo-lo-puede\/","og_locale":"es_ES","og_type":"article","og_title":"Amor todo lo puede | Musulmanes y Cristianos | Evangelizaci\u00f3n al Mundo Isl\u00e1mico","og_description":"Amor todo lo puede - El Cristianismo, el concepto de amor y perd\u00f3n, en muchas ocasiones se pone a prueba cuando los extremistas abrazan la inmundicia al ext","og_url":"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-todo-lo-puede\/","og_site_name":"Jesus Christ for Muslims","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-todo-lo-puede\/","url":"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-todo-lo-puede\/","name":"Amor todo lo puede | Musulmanes y Cristianos | Evangelizaci\u00f3n al Mundo Isl\u00e1mico","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/#website"},"description":"Amor todo lo puede - El Cristianismo, el concepto de amor y perd\u00f3n, en muchas ocasiones se pone a prueba cuando los extremistas abrazan la inmundicia al ext","breadcrumb":{"@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-todo-lo-puede\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/amor-todo-lo-puede\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jesuschristformuslims.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Amor todo lo puede"}]},{"@type":"WebSite","@id":"https:\/\/jesuschristformuslims.com\/#website","url":"https:\/\/jesuschristformuslims.com\/","name":"Jesus Christ for Muslims","description":"Inviting Muslims to the Kingdom of Christ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jesuschristformuslims.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags\/6562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts?tags=6562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}