{"id":6655,"count":1,"description":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">72 v\u00edrgenes esperando en el para\u00edso especial espera tras la muerte a quienes hayan dado su vida por Al\u00e1 en el combate de la yihad, la guerra santa. Esta promesa explica en parte el \u00e9xito del reclutamiento de radicales por parte del Estado Isl\u00e1mico (EI) en los c\u00edrculos m\u00e1s fundamentalistas del mundo musulm\u00e1n. Y tambi\u00e9n el car\u00e1cter arrollador de su ofensiva militar en Irak. Los combatientes del EI no temen la muerte porque muchos est\u00e1n convencidos del ed\u00e9n que les aguarda si caen bajo la insignia negra del autoproclamado califato.<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Desde el siglo X hasta nuestros d\u00edas, la doctrina tradicional de gran parte de los eruditos musulmanes coincide en se\u00f1alar que Dios bendecir\u00e1 de modo especial a los \u00abm\u00e1rtires de la yihad\u00bb con siete se\u00f1ales o recompensas. Una de ellas es la concesi\u00f3n a los varones de 72 mujeres v\u00edrgenes (\u00abhur\u00edes\u00bb). Las mujeres, en cambio, recibir\u00e1n en el para\u00edso un solo hombre \u00abcon el que estar\u00e1n satisfechas\u00bb.<\/span><\/p>\r\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En diversas colecciones de hadiz -relaciones de dichos y hechos del profeta Mahoma tal como fueron recogidos por sus disc\u00edpulos- la figura de las v\u00edrgenes entregadas como recompensa a los justos tiene siempre claros perfiles sensuales y en ocasiones hasta er\u00f3ticos. Los autores fundamentan sus promesas en textos del Cor\u00e1n. Una cita muy conocida describe el car\u00e1cter voluptuoso de las hur\u00edes (\u00abCiertamente para los justos habr\u00e1 un cumplimiento de los deseos (del coraz\u00f3n); jardines encerrados y vides y mujeres voluptuosas de la misma edad\u00bb. Cor\u00e1n, 78: 31-33). Otra sura subraya su estado virginal (Cor\u00e1n 55: 72-74). Otra, en fin, sus grandes y amorosos ojos (Cor\u00e1n 44: 54). A diferencia de la interpretaci\u00f3n posterior dada por los hadiz, el Cor\u00e1n no especifica el n\u00famero de doncellas que recibir\u00e1 cada var\u00f3n justo, ni limita esa recompensa a los combatientes de la yihad; pero no deja lugar a dudas sobre la entrega de muchas esposas v\u00edrgenes a los varones.<\/span><\/p>\r\n\r\n<aside class=\"roba-intercalado sin-fondo layer_inpage\"><span id=\"layer_inpage-id\" class=\"creatividad cmv_intext\" style=\"color: #000000;\" data-voc-vam=\"\" data-voc-vam-position=\"layer_inpage\" data-voc-vam-outofpage=\"true\"><\/span><\/aside>\r\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Algunos ex\u00e9getas occidentales, que temen que este aspecto del islam dificulte el \u00abdi\u00e1logo de civilizaciones\u00bb, optan por una versi\u00f3n metaf\u00f3rica de la presencia de v\u00edrgenes junto a los varones llegados al para\u00edso. Se\u00f1alan, adem\u00e1s, que en la iconograf\u00eda cristiana tambi\u00e9n se representan alas y arpas en el cielo junto a los santos. Pero las escrituras sagradas son claras. No cabe en ellas ninguna ambig\u00fcedad sobre el car\u00e1cter exclusivamente espiritual de la felicidad en el m\u00e1s all\u00e1, \u00abporque en la resurrecci\u00f3n ni se casar\u00e1n ni se dar\u00e1n en casamiento, sino que ser\u00e1n como \u00e1ngeles de Dios en el cielo\u00bb (Mateo 22:30).<\/span><\/p>","link":"https:\/\/jesuschristformuslims.com\/es\/tag\/72-virgenes\/","name":"72 v\u00edrgenes","slug":"72-virgenes","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>72 v\u00edrgenes | Cristo para musulmanes | Comparaci\u00f3n entre Islam y Cristianismo<\/title>\n<meta name=\"description\" content=\"72 v\u00edrgenes esperando en el para\u00edso especial espera tras la muerte a quienes hayan dado su vida por Al\u00e1 en el combate de la yihad, la guerra santa. Esta pro\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jesuschristformuslims.com\/es\/tag\/72-virgenes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"72 v\u00edrgenes | Cristo para musulmanes | Comparaci\u00f3n entre Islam y Cristianismo\" \/>\n<meta property=\"og:description\" content=\"72 v\u00edrgenes esperando en el para\u00edso especial espera tras la muerte a quienes hayan dado su vida por Al\u00e1 en el combate de la yihad, la guerra santa. Esta pro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jesuschristformuslims.com\/es\/tag\/72-virgenes\/\" \/>\n<meta property=\"og:site_name\" content=\"Jesus Christ for Muslims\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/72-virgenes\\\/\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/72-virgenes\\\/\",\"name\":\"72 v\u00edrgenes | Cristo para musulmanes | Comparaci\u00f3n entre Islam y Cristianismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\"},\"description\":\"72 v\u00edrgenes esperando en el para\u00edso especial espera tras la muerte a quienes hayan dado su vida por Al\u00e1 en el combate de la yihad, la guerra santa. Esta pro\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/72-virgenes\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/tag\\\/72-virgenes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jesuschristformuslims.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"72 v\u00edrgenes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jesuschristformuslims.com\\\/#website\",\"url\":\"https:\\\/\\\/jesuschristformuslims.com\\\/\",\"name\":\"Jesus Christ for Muslims\",\"description\":\"Inviting Muslims to the Kingdom of Christ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jesuschristformuslims.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"72 v\u00edrgenes | Cristo para musulmanes | Comparaci\u00f3n entre Islam y Cristianismo","description":"72 v\u00edrgenes esperando en el para\u00edso especial espera tras la muerte a quienes hayan dado su vida por Al\u00e1 en el combate de la yihad, la guerra santa. Esta pro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jesuschristformuslims.com\/es\/tag\/72-virgenes\/","og_locale":"es_ES","og_type":"article","og_title":"72 v\u00edrgenes | Cristo para musulmanes | Comparaci\u00f3n entre Islam y Cristianismo","og_description":"72 v\u00edrgenes esperando en el para\u00edso especial espera tras la muerte a quienes hayan dado su vida por Al\u00e1 en el combate de la yihad, la guerra santa. Esta pro","og_url":"https:\/\/jesuschristformuslims.com\/es\/tag\/72-virgenes\/","og_site_name":"Jesus Christ for Muslims","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/72-virgenes\/","url":"https:\/\/jesuschristformuslims.com\/es\/tag\/72-virgenes\/","name":"72 v\u00edrgenes | Cristo para musulmanes | Comparaci\u00f3n entre Islam y Cristianismo","isPartOf":{"@id":"https:\/\/jesuschristformuslims.com\/#website"},"description":"72 v\u00edrgenes esperando en el para\u00edso especial espera tras la muerte a quienes hayan dado su vida por Al\u00e1 en el combate de la yihad, la guerra santa. Esta pro","breadcrumb":{"@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/72-virgenes\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/jesuschristformuslims.com\/es\/tag\/72-virgenes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jesuschristformuslims.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"72 v\u00edrgenes"}]},{"@type":"WebSite","@id":"https:\/\/jesuschristformuslims.com\/#website","url":"https:\/\/jesuschristformuslims.com\/","name":"Jesus Christ for Muslims","description":"Inviting Muslims to the Kingdom of Christ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jesuschristformuslims.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags\/6655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jesuschristformuslims.com\/es\/wp-json\/wp\/v2\/posts?tags=6655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}